{"id":153,"date":"2021-06-26T06:34:48","date_gmt":"2021-06-26T04:34:48","guid":{"rendered":"https:\/\/www.matherika.com\/?page_id=153"},"modified":"2021-06-30T15:25:26","modified_gmt":"2021-06-30T13:25:26","slug":"data-solution","status":"publish","type":"page","link":"https:\/\/www.matherika.com\/it\/data-solution\/","title":{"rendered":"KONNECTED"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;3.22&#8243;][et_pb_fullwidth_header title=&#8221;data solution&#8221; subhead=&#8221;konnected&#8221; header_scroll_down=&#8221;on&#8221; scroll_down_icon=&#8221;%%2%%&#8221; button_one_text=&#8221;visita il sito&#8221; button_one_url=&#8221;https:\/\/www.konnected.market\/kp\/&#8221; background_overlay_color=&#8221;rgba(0,0,0,0.8)&#8221; content_max_width=&#8221;600px&#8221; _builder_version=&#8221;4.9.7&#8243; title_font=&#8221;Poppins|700||on|||||&#8221; title_text_color=&#8221;#edbb5f&#8221; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;2px&#8221; title_line_height=&#8221;1.4em&#8221; content_font=&#8221;Poppins||||||||&#8221; content_font_size=&#8221;16px&#8221; content_letter_spacing=&#8221;1px&#8221; content_line_height=&#8221;2em&#8221; subhead_font=&#8221;Playfair Display|700||on|||||&#8221; subhead_font_size=&#8221;48px&#8221; subhead_letter_spacing=&#8221;3px&#8221; subhead_line_height=&#8221;1.4em&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; background_image=&#8221;https:\/\/www.matherika.com\/wp-content\/uploads\/2021\/06\/consultant-04.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;on&#8221; custom_button_one=&#8221;on&#8221; button_one_border_width=&#8221;1px&#8221; button_one_border_color=&#8221;rgba(255,255,255,0.3)&#8221; button_one_border_radius=&#8221;0px&#8221; button_one_letter_spacing=&#8221;1px&#8221; button_one_font=&#8221;Saira Extra Condensed|600||on|||||&#8221; button_one_icon=&#8221;%%3%%&#8221; button_one_icon_color=&#8221;#edbb5f&#8221; custom_button_two=&#8221;on&#8221; button_two_border_width=&#8221;1px&#8221; button_two_border_color=&#8221;rgba(255,255,255,0.3)&#8221; button_two_border_radius=&#8221;0px&#8221; button_two_letter_spacing=&#8221;1px&#8221; button_two_font=&#8221;Saira Extra Condensed|600||on|||||&#8221; button_two_icon=&#8221;%%3%%&#8221; button_two_icon_color=&#8221;#edbb5f&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;8%||8%|&#8221; link_option_url_new_window=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; button_one_text_color_hover=&#8221;#edbb5f&#8221; button_two_text_color_hover=&#8221;#edbb5f&#8221; button_one_bg_color_hover=&#8221;rgba(0,0,0,0)&#8221; button_two_bg_color_hover=&#8221;rgba(0,0,0,0)&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;on&#8221; button_one_text_color__hover=&#8221;#edbb5f&#8221; button_two_text_color__hover_enabled=&#8221;on&#8221; button_two_text_color__hover=&#8221;#edbb5f&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;on&#8221; button_one_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_two_bg_color__hover_enabled=&#8221;on&#8221; button_two_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; module_class=&#8221;cbutton&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>&nbsp;<\/p>\n<p>Konnected e\u2019 la piattaforma NextGen sviluppata da Matherika Group che ha come obiettivo quello di rendere l\u2019attivit\u00e0 di acquisto pi\u00f9 <b>efficiente, precisa e immediata<\/b>, con lo scopo di trasmettere ai clienti tutta la <b>conoscenza sulle commodities in modo sempre pi\u00f9 <\/b><b>smart<\/b><b>.<\/b><\/p>\n<p>[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;3.22&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;65px|0px|65px|0px|true|&#8221;][et_pb_row _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_video src=&#8221;https:\/\/youtu.be\/7V-bvyOlRt4&#8243; image_src=&#8221;\/\/i.ytimg.com\/vi\/7V-bvyOlRt4\/hqdefault.jpg&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;flip&#8221; animation_delay=&#8221;200ms&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.9.7&#8243; background_color=&#8221;#2f2f2f&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;50px|0px|100px|0px||&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.9.7&#8243; custom_padding=&#8221;|||&#8221; animation_style=&#8221;fade&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;1px|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Playfair Display|700|||||||&#8221; header_2_font_size=&#8221;38px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_3_font=&#8221;Poppins|700||on|||||&#8221; header_3_text_color=&#8221;#edbb5f&#8221; header_3_font_size=&#8221;14px&#8221; header_3_letter_spacing=&#8221;1px&#8221; header_3_line_height=&#8221;2em&#8221; locked=&#8221;off&#8221;]<\/p>\n<h3>piattaforma nextgen<\/h3>\n<h2><span style=\"color: #ffffff;\">Oltre le analisi standard<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#edbb5f&#8221; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;3.2&#8243; max_width=&#8221;60px&#8221; module_alignment=&#8221;left&#8221; height=&#8221;2px&#8221; locked=&#8221;off&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;16px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;2em&#8221; max_width=&#8221;550px&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><span style=\"color: #ffffff;\">Grazie al sofisticato <b>motore KAI<\/b> (Konnected Artificial Intelligence) <b>\u00e8 possibile monitorare sempre e facilmente l\u2019equilibrio della posizione fisica e finanziaria, con aggiornamenti <\/b><b>real<\/b><b> time dei\u00a0 margini operativi.<\/b><\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.konnected.market\/kp\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;prova la piattaforma&#8221; _builder_version=&#8221;4.9.7&#8243; custom_button=&#8221;on&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;RGBA(0,0,0,0)&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;rgba(255,255,255,0.3)&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Saira Extra Condensed|600||on|||||&#8221; button_icon=&#8221;%%3%%&#8221; button_icon_color=&#8221;#edbb5f&#8221; button_text_color_hover=&#8221;#edbb5f&#8221; button_letter_spacing_hover=&#8221;1px&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#edbb5f&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;on|hover&#8221; button_border_width__hover=&#8221;&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;1px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;5%|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.matherika.com\/wp-content\/uploads\/2021\/06\/Picture1-4.png&#8221; title_text=&#8221;Picture1&#8243; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-105px|||||&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px|||||&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Clients&#8221; _builder_version=&#8221;3.22&#8243; custom_padding=&#8221;100px|0px|100px|0px&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Playfair Display|700|||||||&#8221; header_2_font_size=&#8221;38px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_3_font=&#8221;Poppins|700||on|||||&#8221; header_3_text_color=&#8221;#edbb5f&#8221; header_3_font_size=&#8221;14px&#8221; header_3_letter_spacing=&#8221;1px&#8221; header_3_line_height=&#8221;2em&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; locked=&#8221;off&#8221;]<\/p>\n<h2>Compatibile con i principali brokers internazionali<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#edbb5f&#8221; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;3.2&#8243; max_width=&#8221;60px&#8221; module_alignment=&#8221;center&#8221; height=&#8221;2px&#8221; locked=&#8221;off&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; _builder_version=&#8221;4.9.7&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.matherika.com\/wp-content\/uploads\/2021\/06\/Untitled-1-copy.png&#8221; title_text=&#8221;Untitled-1 copy&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.9.7&#8243; animation_style=&#8221;zoom&#8221; animation_delay=&#8221;400ms&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Konnected e\u2019 la piattaforma NextGen sviluppata da Matherika Group che ha come obiettivo quello di rendere l\u2019attivit\u00e0 di acquisto pi\u00f9 efficiente, precisa e immediata, con lo scopo di trasmettere ai clienti tutta la conoscenza sulle commodities in modo sempre pi\u00f9 smart.piattaforma nextgen Oltre le analisi standardGrazie al sofisticato motore KAI (Konnected Artificial Intelligence) \u00e8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-153","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KONNECTED - Matherika Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matherika.com\/data-solution\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KONNECTED - Matherika Group\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Konnected e\u2019 la piattaforma NextGen sviluppata da Matherika Group che ha come obiettivo quello di rendere l\u2019attivit\u00e0 di acquisto pi\u00f9 efficiente, precisa e immediata, con lo scopo di trasmettere ai clienti tutta la conoscenza sulle commodities in modo sempre pi\u00f9 smart.piattaforma nextgen Oltre le analisi standardGrazie al sofisticato motore KAI (Konnected Artificial Intelligence) \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matherika.com\/data-solution\/\" \/>\n<meta property=\"og:site_name\" content=\"Matherika Group\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-30T13:25:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matherika.com\\\/data-solution\\\/\",\"url\":\"https:\\\/\\\/www.matherika.com\\\/data-solution\\\/\",\"name\":\"KONNECTED - Matherika Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matherika.com\\\/#website\"},\"datePublished\":\"2021-06-26T04:34:48+00:00\",\"dateModified\":\"2021-06-30T13:25:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matherika.com\\\/data-solution\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matherika.com\\\/data-solution\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matherika.com\\\/data-solution\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.matherika.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KONNECTED\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matherika.com\\\/#website\",\"url\":\"https:\\\/\\\/www.matherika.com\\\/\",\"name\":\"Matherika Group\",\"description\":\"Beyond Metals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matherika.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KONNECTED - Matherika Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matherika.com\/data-solution\/","og_locale":"it_IT","og_type":"article","og_title":"KONNECTED - Matherika Group","og_description":"&nbsp; Konnected e\u2019 la piattaforma NextGen sviluppata da Matherika Group che ha come obiettivo quello di rendere l\u2019attivit\u00e0 di acquisto pi\u00f9 efficiente, precisa e immediata, con lo scopo di trasmettere ai clienti tutta la conoscenza sulle commodities in modo sempre pi\u00f9 smart.piattaforma nextgen Oltre le analisi standardGrazie al sofisticato motore KAI (Konnected Artificial Intelligence) \u00e8 [&hellip;]","og_url":"https:\/\/www.matherika.com\/data-solution\/","og_site_name":"Matherika Group","article_modified_time":"2021-06-30T13:25:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.matherika.com\/data-solution\/","url":"https:\/\/www.matherika.com\/data-solution\/","name":"KONNECTED - Matherika Group","isPartOf":{"@id":"https:\/\/www.matherika.com\/#website"},"datePublished":"2021-06-26T04:34:48+00:00","dateModified":"2021-06-30T13:25:26+00:00","breadcrumb":{"@id":"https:\/\/www.matherika.com\/data-solution\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matherika.com\/data-solution\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.matherika.com\/data-solution\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.matherika.com\/it\/"},{"@type":"ListItem","position":2,"name":"KONNECTED"}]},{"@type":"WebSite","@id":"https:\/\/www.matherika.com\/#website","url":"https:\/\/www.matherika.com\/","name":"Matherika Group","description":"Beyond Metals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matherika.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/pages\/153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/comments?post=153"}],"version-history":[{"count":12,"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/pages\/153\/revisions"}],"predecessor-version":[{"id":278,"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/pages\/153\/revisions\/278"}],"wp:attachment":[{"href":"https:\/\/www.matherika.com\/it\/wp-json\/wp\/v2\/media?parent=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}